{"id":28006,"date":"2026-04-22T16:59:47","date_gmt":"2026-04-22T14:59:47","guid":{"rendered":"https:\/\/www.obalne-galerije.si\/?p=28006"},"modified":"2026-04-26T17:39:35","modified_gmt":"2026-04-26T15:39:35","slug":"appuntamenti-di-maggio-2026","status":"publish","type":"post","link":"https:\/\/www.obalne-galerije.si\/it\/appuntamenti-di-maggio-2026\/","title":{"rendered":"APPUNTAMENTI DI MAGGIO 2026"},"content":{"rendered":"<p><!--more--><\/p>\n<p><span style=\"text-decoration: underline;\"><strong>Spettacolo di teatro musicale Il triangolo di Marko Brecelj (Rotulus Homo Pendulum) nella Sala lignea del Monfort a Portorose<\/strong><\/span><\/p>\n<p>Nel mese di maggio le Gallerie Costiere Pirano, l&#8217;Associazione degli Amici del Progresso Moderato (DPZN), l&#8217;Istituto DELAK e la Casa del teatro musicale estremo (Zagabria) organizzano lo spettacolo multimediale Il triangolo di Marko Brecelj (Rotulus Homo Pendulum), opera d&#8217;autore del gruppo composto da Zlatko Buri\u0107 Ki\u0107o, Damir Bartol Indo\u0161 e Tanja Vrvilo dalla Croazia, Dragana Milutinovi\u0107 dalla Serbia, nonch\u00e9 Dragan \u017divadinov e Aljo\u0161a \u017divadinov Zupan\u010di\u010d dalla Slovenia.<\/p>\n<p>Lo spettacolo, in programma nella <strong>Sala lignea del Monfort a Portorose il 9 e 10 maggio 2026<\/strong>, attualizza gli effetti e le modalit\u00e0 dell&#8217;azione emancipatoria derivante dalle pratiche teatrali del gruppo neoavanguardista <em>Kugla glumi\u0161te<\/em>, in collaborazione con artisti teatrali, visivi e musicali di sensibilit\u00e0 artistica affine a quella di Marko Brecelj. Il progetto estremo di teatro musicale opera nell&#8217;ambito dell&#8217;estetica della memoria pubblica e privata intesa come bene comune. Prende le mosse dall&#8217;opera artistica del poeta, performer, musicista e attivista Marko Brecelj. Si sviluppa a partire dalle sue numerose forme di artivismo e apre il suo diario \u00bb<em>Dodogovor<\/em>\u00ab, che infrange le distinzioni tra pubblico e privato, storico e attuale, assoluto e contingente.<\/p>\n<p>I partner del progetto sono: Comune di Pirano, Auditorium Portorose, Ministero della Cultura della RS, Fondazione Battaglione del Pohorje, AMZS, Citt\u00e0 di Zagabria, Ministero della Cultura della Repubblica di Croazia, Fondazione Kultura nova, Jazz Denmark.<\/p>\n<p><strong>L&#8217;ingresso \u00e8 gratuito con biglietto omaggio, da ritirare online o presso la biglietteria dell&#8217;Auditorium Portorose. Il numero di biglietti \u00e8 limitato.<\/strong><\/p>\n<p><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.obalne-galerije.si\/it\/triangolo-di-marko-brecelj-rotulus-homo-pendulum\/\">Maggiori informazioni al link\u2026<\/a><\/span><\/p>\n<hr \/>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong><u>Mostra del rinomato designer Dragan Sakan, intitolata Sakan e Pirano, alla Galleria Herman Pe\u010dari\u010d di Pirano<\/u><\/strong><\/p>\n<p><strong>Dragan Sakan<\/strong> (1950\u20132010), psicologo di formazione, \u00e8 stato un pioniere della pubblicit\u00e0 in Serbia e negli altri Paesi della regione. \u00c8 stato direttore creativo, uomo di visione e di successi, una delle prime personalit\u00e0 riconoscibili del nostro spazio imprenditoriale. Per lui la pubblicit\u00e0 non era soltanto una professione, ma un modo di vivere. Con la sua passione e la sua incisivit\u00e0 ha plasmato l&#8217;industria pubblicitaria e ha raccolto attorno a s\u00e9 i migliori creativi dell&#8217;ex Jugoslavia. Il suo principio guida era semplice ma penetrante: aiutare le persone e le aziende a risplendere in tutto il loro splendore.<\/p>\n<p>Sakan era strettamente legato a Pirano, citt\u00e0 che proprio grazie a lui \u00e8 entrata nella mappa mondiale della creativit\u00e0. Qui nacquero idee che segnarono il suo percorso creativo: dal passaggio allo Studio Marketing Delo allo sviluppo del Saatchi &amp; Saatchi mondiale nei Balcani, fino alla fondazione dell&#8217;agenzia New Moment e del festival Idea Campus.<\/p>\n<p>Per onorarne la memoria, nel 2011 la famiglia ha donato al Comune di Pirano una scultura in bronzo realizzata su sua idea. L&#8217;opera rappresenta Pirano come citt\u00e0 culturale e creativa e si trova sul lungomare davanti al Teatro Tartini. Quest&#8217;anno Pirano gli rende nuovamente omaggio, questa volta con la mostra Sakan e Pirano, realizzata in collaborazione con l&#8217;Ambasciata della Repubblica di Serbia in Slovenia, il primo consigliere Aleksandar Gatalica, la famiglia Sakan e i suoi amici, con il sostegno del Comune di Pirano e delle Gallerie Costiere Pirano. L&#8217;allestimento presenta una selezione di fotografie dei primi anni creativi e dei primi incontri di Sakan con Pirano, nonch\u00e9 dei periodi dei suoi maggiori successi, condivisi con questa citt\u00e0. Comprende anche il periodo in cui soggiornava a Pirano e vi ospitava leggende dell&#8217;arte e della pubblicit\u00e0 mondiale. Un posto speciale \u00e8 riservato ai momenti d&#8217;ispirazione: sulla nave New e in Piazza Tartini, dove \u00absi vede bene solo con il cuore\u00bb.<\/p>\n<p>I curatori della mostra, che inaugureremo alla<strong> Galleria Herman Pe\u010dari\u010d gioved\u00ec 14 maggio<\/strong> <strong>2026 alle ore 18<\/strong>, sono <strong>Lazar Sakan<\/strong> e <strong>Slavoljub Stankovi\u0107<\/strong>. La mostra sar\u00e0 visitabile fino al 16 agosto 2026.<\/p>\n<p><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.obalne-galerije.si\/it\/sakan-e-pirano\/\">Maggiori informazioni al link\u2026<\/a><\/span><\/p>\n<hr \/>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong><u>Grande mostra retrospettiva di Bernhard R\u00fcdiger, intitolata Ancora sbagliato (settima tromba), alla Galleria Civica di Pirano<\/u><\/strong><\/p>\n<p>Da maggio fino alla fine dell&#8217;estate la Galleria Civica di Pirano ospiter\u00e0 una grande mostra personale dell&#8217;artista di fama internazionale <strong>Bernhard R\u00fcdiger<\/strong> (Roma, 1964), che rientra nel ristretto novero delle principali mostre di rilevanza nazionale. Nella mostra, che inaugureremo <strong>venerd\u00ec<\/strong> <strong>22 maggio 2026 alle ore 19.00<\/strong>, sar\u00e0 presentata una selezione di opere fondamentali del suo ricco percorso creativo, lungo quasi quarant&#8217;anni: sculture, installazioni, disegni, dipinti, proiezioni sonore, film e altro.<\/p>\n<p>R\u00fcdiger ha formato la propria espressione artistica in dialogo con gli sconvolgimenti sociali, politici e storici del periodo 1985\u20132025, che \u00e8 stato anche il suo periodo creativo pi\u00f9 intenso. Le opere d&#8217;arte di alto livello non sono soltanto oggetti visivi, ma interventi che coinvolgono il suono, le vibrazioni e l&#8217;esperienza corporea del visitatore. Il senso dell&#8217;allestimento consiste nello spostare lo spettatore da un ruolo passivo a uno attivo e nel presentare l&#8217;arte come qualcosa che si percepisce con tutto il corpo, attraverso tutti i sensi, e non solo con lo sguardo. Le sue sculture e installazioni spaziali pongono la questione di come percepiamo la forma e l&#8217;arte in un tempo in cui le forze storiche (guerre, violenza, capitalismo neoliberale, catastrofi naturali) plasmano la nostra realt\u00e0. L&#8217;interesse dell&#8217;artista \u00e8 superare i confini dell&#8217;estetica e aprire una riflessione sui rapporti globali di potere, sui confini invisibili, sulla violenza e sull&#8217;economia come motore dei conflitti contemporanei. Allo stesso modo, la riflessione dell&#8217;artista sul rapporto, ovvero sull&#8217;interazione, tra arte, societ\u00e0 e storia contemporanea ci collegher\u00e0 a una pi\u00f9 ampia comprensione dell&#8217;arte contemporanea e delle correnti artistiche mondiali.<\/p>\n<p>I curatori della mostra sono <strong>Mara Ambro\u017ei\u010d Verderber<\/strong>, direttrice delle Gallerie Costiere Pirano, e <strong>Matic Bukovac<\/strong>. Alla mostra collaborano anche l&#8217;Universit\u00e0 di Lione (UDL): <em>\u00c9cole <\/em><em>Nationale Sup\u00e9rieure des Beaux-Arts<\/em> (ENSBA) e il museo <em>Terra <\/em>di Kikinda, in Serbia.<\/p>\n<p>In occasione della mostra sar\u00e0 organizzato un ricco programma collaterale. Gi\u00e0 sabato 23 maggio 2026, mentre l&#8217;artista sar\u00e0 ancora a Pirano, si unir\u00e0 a noi per una visita guidata trilingue della mostra alle ore 11.00.<\/p>\n<p><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.obalne-galerije.si\/it\/bernhard-rudiger-ancora-sbagliato-settima-tromba\/\">Maggiori informazioni al link\u2026<\/a><\/span><\/p>\n<hr \/>\n<p><strong><em>\u00a0<\/em><\/strong><\/p>\n<p><strong><u>Collaborazione con il Dipartimento di Arti visive e design della Facolt\u00e0 di Pedagogia dell&#8217;Universit\u00e0 del Litorale.<\/u><\/strong><\/p>\n<p>La Galleria Medusa di Capodistria ospiter\u00e0 due progetti nati in collaborazione con la Facolt\u00e0 di Pedagogia dell&#8217;Universit\u00e0 del Litorale. Il primo \u00e8 il <strong>performans di un giorno Overscroll<\/strong>, che <strong>marted\u00ec 5<\/strong> <strong>maggio 2026<\/strong> sar\u00e0 realizzato alla <strong>Galleria Meduza<\/strong> dall&#8217;autore <strong>Marko Mladenovi\u0107<\/strong>, studente del Dipartimento di Arti visive e design della Facolt\u00e0 di Pedagogia dell&#8217;Universit\u00e0 del Litorale, sotto la mentorship del <strong>prof. Nemanja Cvijanovi\u0107<\/strong>. Il performans si riferisce al pi\u00f9 grande problema del XXI secolo: la dipendenza dai social network e dai telefoni cellulari. La sovrabbondanza di informazioni superflue, che blocca la nostra capacit\u00e0 di pensare e di ragionare, conduce alle malattie dell&#8217;epoca contemporanea, come depressione, ansia, alienazione e disumanizzazione. Poich\u00e9 siamo tutti costretti ad avere telefoni cellulari, questo problema diventa un problema di tutti noi: il mondo intero, dunque, condivide lo stesso problema. Sponsor del performans \u00e8 l&#8217;azienda Paloma.<\/p>\n<p>Seguir\u00e0 il progetto <em>Laboratorio urbano<\/em>, ideato nel 2024 dal <strong>doc. dott. Bo\u0161tjan <\/strong>Bugari\u010d. Sotto la sua mentorship creeranno gli <strong>studenti e le studentesse del 1\u00b0 anno del Dipartimento di Arti visive e design<\/strong> (UP PEF VUO). Lo spazio espositivo della galleria funge qui da quadro di ricerca unitario, nel quale testi, spazio, immagine e suono si intrecciano in una narrazione comune. La mostra non \u00e8 soltanto la presentazione del risultato finale, ma un campo aperto di produzione del sapere, in cui approcci documentari, pratiche artistiche e interventi spaziali si incontrano nel momento del loro farsi. <strong><em>Laboratorio urbano II<\/em><\/strong> prender\u00e0 avvio alla <strong>Galleria Medusa<\/strong> il 12 maggio; la mostra inaugurer\u00e0 <strong>gioved\u00ec 28 maggio<\/strong> e sar\u00e0 visitabile fino al 5 giugno 2026.<\/p>\n<p>Maggiori informazioni al link\u2026<\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n<p><strong><u>Attivit\u00e0 pedagogiche e andragogiche<\/u><\/strong><\/p>\n<p>Nel mese di maggio proseguiamo con i <strong>laboratori pedagogici e le visite guidate<\/strong> collegati alle mostre in corso: <em>Gallerie Costiere Pirano \u2013 50 anni di arte contemporanea<\/em>, selezione dalla <em>Collezione Herman Pe\u010dari\u010d<\/em> e <em>I mostri sono umani<\/em>.<\/p>\n<p>Come ogni anno, anche quest&#8217;anno, con il clima primaverile pi\u00f9 mite, nel parco delle sculture <strong>Forma viva Portorose<\/strong> prenderanno il via i laboratori <strong><em>Scolpiamo insieme!<\/em><\/strong> Proseguono inoltre i <strong>laboratori<\/strong> <strong>andragogici<\/strong> dedicati ai cittadini anziani, che si svolgono ogni primo luned\u00ec del mese presso il <strong>Centro diurno \u0160koljka a Pirano<\/strong>.<\/p>\n<p>Le Gallerie Costiere Pirano collaborano alla <strong><em>Scuola di cultura<\/em><\/strong>, un intenso progetto nazionale triennale di educazione culturale e artistica volto a collegare gli istituti educativo-formativi e le istituzioni culturali a livello regionale (Fondo sociale europeo + e Ministero della Cultura della Repubblica di Slovenia) per alunni_e del terzo ciclo delle scuole elementari e studenti_esse delle scuole secondarie (2025\u20132029).<\/p>\n<p>Maggiori informazioni saranno pubblicate sul sito web delle Gallerie Costiere Pirano.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Siete cordialmente invitati, saremo lieti di incontrarvi.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":28003,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-28006","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.obalne-galerije.si\/it\/wp-json\/wp\/v2\/posts\/28006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.obalne-galerije.si\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.obalne-galerije.si\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.obalne-galerije.si\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.obalne-galerije.si\/it\/wp-json\/wp\/v2\/comments?post=28006"}],"version-history":[{"count":3,"href":"https:\/\/www.obalne-galerije.si\/it\/wp-json\/wp\/v2\/posts\/28006\/revisions"}],"predecessor-version":[{"id":28040,"href":"https:\/\/www.obalne-galerije.si\/it\/wp-json\/wp\/v2\/posts\/28006\/revisions\/28040"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.obalne-galerije.si\/it\/wp-json\/wp\/v2\/media\/28003"}],"wp:attachment":[{"href":"https:\/\/www.obalne-galerije.si\/it\/wp-json\/wp\/v2\/media?parent=28006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.obalne-galerije.si\/it\/wp-json\/wp\/v2\/categories?post=28006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.obalne-galerije.si\/it\/wp-json\/wp\/v2\/tags?post=28006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}