{"id":26032,"date":"2025-10-15T10:51:26","date_gmt":"2025-10-15T08:51:26","guid":{"rendered":"https:\/\/www.obalne-galerije.si\/?p=26032"},"modified":"2025-10-20T12:33:02","modified_gmt":"2025-10-20T10:33:02","slug":"13-festival-darte-contemporanea-e-intermediale-izis-fine-del-messaggio","status":"publish","type":"post","link":"https:\/\/www.obalne-galerije.si\/it\/13-festival-darte-contemporanea-e-intermediale-izis-fine-del-messaggio\/","title":{"rendered":"13\u00b0 FESTIVAL D&#8217;ARTE CONTEMPORANEA E INTERMEDIALE IZIS: FINE DEL MESSAGGIO"},"content":{"rendered":"<p><section class=\"kc-elm kc-css-52342 kc_row\"><div class=\"kc-row-container  kc-container\"><div class=\"kc-wrap-columns\"><div class=\"kc-elm kc-css-111074 kc_col-sm-12 kc_column kc_col-sm-12\"><div class=\"kc-col-container\"><\/div><\/div><\/div><\/div><\/section><section class=\"kc-elm kc-css-845523 kc_row\"><div class=\"kc-row-container  kc-container\"><div class=\"kc-wrap-columns\"><div class=\"kc-elm kc-css-743156 kc_col-sm-6 kc_column kc_col-sm-6\"><div class=\"kc-col-container\"><div class=\"kc-elm kc-css-140310 kc_text_block\"><\/p>\n<p><strong>13\u00b0 Festival d\u2019arte contemporanea e intermediale IZIS:<\/strong><br \/><strong>FINE DEL MESSAGGIO |\u00a0<\/strong><\/p>\n<p><strong>Galleria Loggia, Capodistria, 17 ottobre \u2013 2 novembre 2025 |\u00a0<\/strong><br \/><strong>Inaugurazione: 17 ottobre, ore 19:00 |\u00a0<\/strong><\/p>\n<p><strong>Artiste e artisti: Sara Bezov\u0161ek e Dorijan \u0160i\u0161ko, Sanela Jahi\u0107, PlateauResidue + Samo Kutin ed Enja Grabijan, \u0160pela Petri\u010d, Maja Smrekar |\u00a0<\/strong><\/p>\n<p><strong>Curatrice: Irena Bori\u0107.<\/strong><\/p>\n<p><!--more--><\/p>\n<p>\n<\/div><div class=\"kc-elm kc-css-206237\" style=\"height: 20px; clear: both; width:100%;\"><\/div>\n<div class=\"kc-elm kc-css-777714\">\n\t<a class=\"kc_button\" href=\"https:\/\/www.obalne-galerije.si\/wp-content\/uploads\/2025\/10\/IZIS_XIII_Vabilo_A4_SI-IT-EN.pdf\" target=\"_blank\" title=\"\" onclick=\"\">\n\t\t<i class=\"sl-paper-clip\"><\/i> INVITO: DOWNLOAD\t<\/a>\n<\/div>\n<div class=\"kc-elm kc-css-408750\" style=\"height: 20px; clear: both; width:100%;\"><\/div><div class=\"kc-elm kc-css-522818 kc_shortcode kc_single_image\">\n\n        <img decoding=\"async\" src=\"https:\/\/www.obalne-galerije.si\/wp-content\/uploads\/2025\/10\/1_SPASM_by_Maja_Smrekar_a_political-scaled.jpg\" class=\"\" alt=\"\" \/>    <\/div>\n<div class=\"kc-elm kc-css-604376 kc_text_block\"><\/p>\n<p><small><em>Maja Smrekar fotografgija: navedba: SPASM by Maja Smrekar and A\/POLITICAL, 3D scan and rendering: FBFX Digital, 2024.<\/em><\/small><\/p>\n<p>\n<\/div><div class=\"kc-elm kc-css-229950 kc_shortcode kc_single_image\">\n\n        <img decoding=\"async\" src=\"https:\/\/www.obalne-galerije.si\/wp-content\/uploads\/2025\/10\/2_Plateauresidue-scaled.jpg\" class=\"\" alt=\"\" \/>    <\/div>\n<div class=\"kc-elm kc-css-35589 kc_text_block\"><\/p>\n<p><small><em>PlateauResidue + Samo Kutin in Enja Grabrijan: Anima Spirare: Eolova harfa, 2025.<\/em><\/small><\/p>\n<p>\n<\/div><div class=\"kc-elm kc-css-698943 kc_shortcode kc_single_image\">\n\n        <img decoding=\"async\" src=\"https:\/\/www.obalne-galerije.si\/wp-content\/uploads\/2025\/10\/3_Sanela-Jahic-scaled.jpg\" class=\"\" alt=\"\" \/>    <\/div>\n<div class=\"kc-elm kc-css-602624 kc_text_block\"><\/p>\n<p><small><em>Sanela Jahi\u0107: Ne umetni inteligenci, Da nefa\u0161isti\u010dnemu aparatu, 2023.<\/em><\/small><\/p>\n<p>\n<\/div><div class=\"kc-elm kc-css-390626\" style=\"height: 20px; clear: both; width:100%;\"><\/div><\/div><\/div><div class=\"kc-elm kc-css-695669 kc_col-sm-6 kc_column kc_col-sm-6\"><div class=\"kc-col-container\"><div class=\"kc-elm kc-css-820211 kc_text_block\"><\/p>\n<p><span style=\"font-style: inherit; font-family: -apple-system, BlinkMacSystemFont,;\">La\u00a0tredicesima edizione del festival IZIS\u00a0tematizza il\u00a0rumore informativo\u00a0ed esplora le (in)capacit\u00e0 di comunicazione nell\u2019epoca del capitalismo della comunicazione. Si interroga su cosa accada al messaggio in mezzo alla massa di\u00a0post-verit\u00e0, disinformazione, fake news, ma anche di\u00a0iperinflazione di immagini e contenuti generati dalle macchine, come i\u00a0<\/span><em style=\"font-family: -apple-system, BlinkMacSystemFont,;\">bot<\/em><span style=\"font-style: inherit; font-family: -apple-system, BlinkMacSystemFont,;\">\u00a0o l\u2019intelligenza artificiale. Il festival si chiede:\u00a0il messaggio inviato ha davvero un destinatario?\u00a0E come, in un\u2019epoca di circolazione frammentata e priva di senso delle informazioni, possiamo affrontare questioni urgenti e comunicare in modo diverso?<\/span><\/p>\n<p>Il\u00a0programma del festival IZIS 2025\u00a0si estende su vari luoghi a Capodistria \u2013 la\u00a0Galleria Laggia, la\u00a0Galleria del Palazzo Gravisi-Buttorai, la\u00a0fortezza Bastion\u00a0e due container navali. Questa edizione,\u00a0spazialmente frammentata, che si svolge dal\u00a017 ottobre al 2 novembre 2025, collega differenti sezioni del programma \u2013\u00a0intermediale, musicale e performativo\u00a0\u2013 sottolineandone l\u2019interconnessione concettuale e tematica.<\/p>\n<p>Alla\u00a0Galleria Laggia\u00a0\u00e8 allestita la\u00a0mostra principale del festival,\u00a0<em>Fine del messaggio<\/em>, che presenta le opere di\u00a0Sara Bezov\u0161ek e Dorijan \u0160i\u0161ko, Sanela Jahi\u0107, PlateauResidue + Samo Kutin ed Enja Grabijan, \u0160pela Petri\u010d e Maja Smrekar. La sigla standard\u00a0<em>End of Message<\/em>\u00a0(EOM), che indica la fine di un messaggio elettronico che\u00a0non prevede risposta, funziona qui come\u00a0metafora della comunicazione interrotta e priva di significato. Lo\u00a0spazio del dialogo\u00a0viene offuscato da un\u00a0rumore di fondo sempre pi\u00f9 intenso, e la mostra affronta cos\u00ec\u00a0le molteplici dimensioni della comprensione e dell\u2019incomprensione\u00a0nei mondi\u00a0non umani e pi\u00f9-che-umani.<\/p>\n<p>Sara Bezov\u0161ek e Dorijan \u0160i\u0161ko, con l\u2019opera\u00a0<em>Black Box<\/em>, illustrano la\u00a0condizionalit\u00e0 ideologica e identitaria\u00a0della comunicazione nella sfera digitale. Il formato del videogioco offre uno\u00a0sguardo sulla paesaggistica memetica, in cui il giocatore pu\u00f2 avanzare solo\u00a0scegliendo tra diverse \u201cpillole\u201d, anche se la scelta\u00a0non \u00e8 necessariamente sua.\u00a0<em>Black Box <\/em>rappresenta un estratto di un sistema in cui\u00a0gli ingressi ideologici e identitari influenzano le reazioni in uscita.<\/p>\n<p>Nell\u2019epoca dell\u2019intelligenza artificiale, il messaggio\u00a0non \u00e8 pi\u00f9 necessariamente umano, cos\u00ec come la conversazione guidata\u00a0non \u00e8 pi\u00f9 necessariamente interumana. Tuttavia, come rivela\u00a0Sanela Jahi\u0107\u00a0nel suo video\u00a0<em>No all\u2019IA, s\u00ec a un apparato non fascista<\/em>, le modalit\u00e0 di utilizzo dell\u2019intelligenza artificiale come\u00a0strumento tecnologico\u00a0favoriscono un \u201c<em>passaggio verso l\u2019autoritarismo, presente nell\u2019industria tecnologica stessa, nella politica di vari Stati e istituzioni e nella crescita dei movimenti politici di estrema destra<\/em>\u201d. L\u2019intelligenza artificiale, dunque,\u00a0non \u00e8 una tecnologia neutrale, ma \u00e8 nuovamente condizionata da\u00a0posizioni di potere ideologiche e identitarie.<\/p>\n<p>Il\u00a0foto-performans\u00a0<em>Spasm<\/em>\u00a0di Maja Smrekar\u00a0mostra il corpo dell\u2019artista in un\u00a0abbraccio convulso con la macchina. Osservando il contrasto tra la pelle e la superficie metallica lucente, forse non ci accorgiamo che\u00a0non stiamo guardando l\u2019artista reale: il suo corpo \u00e8 stato infatti\u00a0scansionato da 234 telecamere, producendo una\u00a0versione digitale iper-dettagliata. L\u2019opera \u00e8 un frammento di un video in lavorazione che affronta, tra l\u2019altro, il tema della\u00a0morte\u00a0e l\u2019illusione di superarla\u00a0attraverso la tecnologia. Affrontando le\u00a0incertezze umane e tecnologiche, il lavoro mette in luce\u00a0come l\u2019intelligenza artificiale possa generare vere e proprie allucinazioni.<\/p>\n<p>Con un tocco di\u00a0umorismo,\u00a0\u0160pela Petri\u010d\u00a0riflette in modo speculativo sulla\u00a0possibilit\u00e0 di un dialogo tra piante e esseri umani. Partendo da una\u00a0prospettiva antropocentrica, osserva le\u00a0migliaia di stomi di un ficus\u00a0come\u00a0migliaia di \u201cbocche\u201d, interpretandone l\u2019apertura e la chiusura tramite un\u00a0esperto di lettura labiale\u00a0e con l\u2019aiuto dell\u2019intelligenza artificiale. Il\u00a0nonsense\u00a0che deriva da questa interpretazione illustra i\u00a0limiti della prospettiva umana\u00a0nel tentativo di comprendere tali forme di comunicazione.<\/p>\n<p>L\u2019opera\u00a0<em>Anima Spirare<\/em>, realizzata in collaborazione tra\u00a0PlateauResidue, Samo Kutin ed Enja Grabijan, affronta anch\u2019essa l\u2019incapacit\u00e0 umana di comprendere i messaggi\u00a0che sono costantemente presenti nell\u2019ambiente. <em>Anima Spirare<\/em>\u00a0significa\u00a0\u201cespirare\u201d\u00a0e richiama cos\u00ec l\u2019idea di una\u00a0fine, non solo linguistica. L\u2019arpa eolica, la cui\u00a0tavola armonica \u00e8 costruita con legno di un abete di 6500 anni, rappresenta il\u00a0messaggio del vento, che per l\u2019uomo rimane\u00a0al di l\u00e0 del tempo e della forma, un messaggio che\u00a0pu\u00f2 soltanto essere ascoltato.<\/p>\n<p>Il Festival IZIS e sostenuto da:<\/p>\n<p>PiNA,\u00a0HEKA,\u00a0Stran22,\u00a0Comune Citt\u00e0 di Capodistria,\u00a0Ministero della Cultura,\u00a0JSKD \u2013 Fondo pubblico della Repubblica di Slovenia per le attivit\u00e0 culturali,\u00a0Gallerie Costiere di Pirano,\u00a0Comunit\u00e0 degli Italiani \u201cSantorio Santorio\u201d di Capodistria,\u00a0Museo Provinciale di Capodistria,\u00a0Universit\u00e0 del Litorale \u2013 Facolt\u00e0 di Scienze della Formazione, Arti visive e Design,\u00a0KUD Format,\u00a0STARTS4WATERII,\u00a0V2 e Ljudmila.<\/p>\n<p>\n<\/div>\n<div class=\"kc-elm kc-css-625141 divider_line\">\n\t<div class=\"divider_inner divider_line1\">\n\t\t\t<\/div>\n<\/div>\n<div class=\"kc-elm kc-css-573703\" style=\"height: 20px; clear: both; width:100%;\"><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"kc-elm kc-css-967039 kc_row\"><div class=\"kc-row-container  kc-container\"><div class=\"kc-wrap-columns\"><div class=\"kc-elm kc-css-718472 kc_col-sm-6 kc_column kc_col-sm-6\"><div class=\"kc-col-container\"><div class=\"kc-elm kc-css-688214 kc_shortcode kc_single_image\">\n\n        <img decoding=\"async\" src=\"https:\/\/www.obalne-galerije.si\/wp-content\/uploads\/2025\/10\/4_Black-Box_5-credit_-Sara-Bezovsek-Dorijan-Sisko.png\" class=\"\" alt=\"\" \/>    <\/div>\n<div class=\"kc-elm kc-css-445034 kc_text_block\"><\/p>\n<p><small><em>Sara Bezov\u0161ek, Dorijan \u0160i\u0161ko: \u010crna \u0161katla, 2025.<\/em><\/small><\/p>\n<p>\n<\/div><div class=\"kc-elm kc-css-758219 kc_shortcode kc_single_image\">\n\n        <img decoding=\"async\" src=\"https:\/\/www.obalne-galerije.si\/wp-content\/uploads\/2025\/10\/5_IFIL_ReadingLips@author_SpelaPetric_author-of-photo_SpelaPetric-scaled.jpg\" class=\"\" alt=\"\" \/>    <\/div>\n<div class=\"kc-elm kc-css-335894 kc_text_block\"><\/p>\n<p><small><em>\u0160pela Petri\u010d, Institut za nezaznavne jezike: branje ustnic, 2025.<\/em><\/small><\/p>\n<p>\n<\/div><div class=\"kc-elm kc-css-191176\" style=\"height: 20px; clear: both; width:100%;\"><\/div><\/div><\/div><div class=\"kc-elm kc-css-539464 kc_col-sm-6 kc_column kc_col-sm-6\"><div class=\"kc-col-container\"><div class=\"kc-elm kc-css-833069 kc_text_block\"><\/p>\n<h3><span style=\"font-size: 1em; font-weight: 600; font-style: inherit; font-family: -apple-system, BlinkMacSystemFont, &#039;Segoe UI&#039;, Roboto, Oxygen-Sans, Ubuntu, Cantarell, &#039;Helvetica Neue&#039;, sans-serif;\">FINE DEL MESSAGGIO<\/span><\/h3>\n<p>\u201cLe organizzazioni mediatiche pi\u00f9 potenti del XXI secolo saranno termiche. La circolazione di immagini, suoni, video e testi dipender\u00e0 da un\u2019estesa modalit\u00e0 di riscaldamento e raffreddamento. I dati e le reti, proprio come le persone che collegano, diventeranno sempre pi\u00f9 fragili. Se far\u00e0 troppo caldo o troppo freddo, le piattaforme crolleranno. L\u2019infrastruttura digitale \u2013 data center, nodi di rete e cavi in fibra ottica \u2013 prosciugher\u00e0 l\u2019energia del pianeta per creare un ambiente termico stabile \u2013 non per le persone, ma per l\u2019informazione.\u201d<\/p>\n<p>Nicole Starosielski, Media Hot and Cold, 2022<\/p>\n<p>La 13\u00aa edizione del festival IZIS tematizza il rumore informativo ed esplora l\u2019(in)capacit\u00e0 di comunicare nell\u2019era del capitalismo della comunicazione. Si interroga su cosa accade ai messaggi in mezzo alla massa di post-verit\u00e0, disinformazione, fake news, nonch\u00e9 all\u2019iperinflazione di immagini e contenuti generati dalle macchine, come bot o intelligenze artificiali. Come influenzano voci, pubblicit\u00e0, raccomandazioni, video virali, filmati privati o pubblici provenienti da zone di guerra o immagini di catastrofi un messaggio che circola nello stesso spazio comunicativo? Forse tutto dipende dalla prospettiva da cui comprendiamo quel messaggio. Da un punto di vista umano, il contenuto \u00e8 influenzato da fattori culturali, linguistici e sociali; per le macchine, invece, tutto \u00e8 una questione di calcolo. Secondo uno dei primi modelli di comunicazione, il modello Shannon-Weaver, il rumore di fondo contestualizza l\u2019informazione, e l\u2019informazione stessa ha bisogno del rumore per essere trasmessa con successo. In altre parole, non esiste informazione senza rumore. Allo stesso tempo, ricevere un\u2019informazione o percepirla non significa comprendere accuratamente il mondo esterno. Come osserva l\u2019artista e scrittore Trevor Paglen, <em>\u201c\/&#8230;\/ il divario tra ci\u00f2 che sentiamo e ci\u00f2 che percepiamo pu\u00f2 essere riempito da ogni tipo di iniezione diretta e allucinazione contraddittoria. La realt\u00e0 diventa cos\u00ec un intreccio complesso di materiale, immaginario, percettibile e impercettibile \u2013 tutti elementi manipolabili.\u201d <\/em>Cosa accade al significato se il messaggio circola in un ambiente in cui i media, come scrive ancora Paglen, <em>\u201c\/&#8230;\/ producono e persuadono, modulano e manipolano, modellano visioni del mondo e azioni per convincerci di ci\u00f2 che vogliono farci credere, traendone valore e influenza\u201d<\/em>?<\/p>\n<p>End of Message (EoM) \u00e8 l\u2019etichetta standard che indica la fine di una comunicazione elettronica, un messaggio che non prevede risposta. Nell&#039;ambito dell\u2019edizione di quest\u2019anno di \u2019IZIS, End of Message diventa una metafora della comunicazione interrotta, priva di senso e spezzata, che non accompagna il dialogo e non ha bisogno di un destinatario per esistere.<\/p>\n<p>La proliferazione infinita di contenuti che forse non raggiungeranno mai il destinatario illustra la sottomissione della comunicazione alla logica economica: la quantit\u00e0 prevale sulla qualit\u00e0. La rappresentazione meccanica coinvolge tutti \u2013 dall\u2019essere umano al bot fino all\u2019intelligenza artificiale generativa \u2013 e allo stesso tempo l\u2019uno imita l\u2019altro, senza sapere chi stia realmente parlando con chi. In questo ambiente iper-profittevole, si percepisce la putrefazione del cadavere di Internet, che si adatta alle priorit\u00e0 delle singole piattaforme e influenza la formazione della soggettivit\u00e0 digitale. Sebbene siamo pienamente consapevoli delle immagini del genocidio in Palestina, l\u2019azione politica per impedirlo \u00e8 paralizzata, e l\u2019informazione esiste solo come dato, non come impulso all\u2019azione. Come scrive l\u2019artista e autore James Bridle nel libro New Dark Age: \u201c<em>\/&#8230;\/ informazione e violenza sono completamente e indissolubilmente legate, e le tecnologie che dovrebbero esercitare controllo sul mondo accelerano l\u2019uso dell\u2019informazione come arma. Sebbene le conseguenze siano visibili ovunque, continuiamo ad attribuire un valore eccessivo all\u2019informazione, che ci imprigiona in cicli ripetuti di violenza, distruzione e morte.<\/em>\u201d<\/p>\n<p>In modo ironico, le conseguenze materiali dell\u2019infrastruttura della comunicazione minacciano le condizioni fondamentali della vita, proprio perch\u00e9 la sfera dei dati e delle informazioni si basa sul tempo e spazio astratti del capitale. L\u2019accesso a un\u2019energia a basso costo non solo presuppone la possibilit\u00e0 di conflitti interpersonali, ma produce anche enormi emissioni di carbonio, inquinamento, rifiuti digitali ed elettronici, e estrazione di materie prime. Pertanto, l\u2019\u201cEnd of Message\u201d affrontato dal festival contiene anche una dimensione materiale, quella che rende possibile il messaggio stesso. Questa volta, non si concentra sulle condizioni materiali della produzione di informazione, ma dispiega differenti modalit\u00e0 di comprensione e comunicazione da prospettive umane e multi-umane.<\/p>\n<p>Irena Bori\u0107, curatrice di IZIS<\/p>\n<p>\n<\/div><div class=\"kc-elm kc-css-552737\" style=\"height: 20px; clear: both; width:100%;\"><\/div><div class=\"kc-elm kc-css-523801 kc_text_block\"><\/p>\n<p><small><span style=\"font-style: inherit; font-family: -apple-system, BlinkMacSystemFont, &#039;Segoe UI&#039;, Roboto, Oxygen-Sans, Ubuntu, Cantarell, &#039;Helvetica Neue&#039;, sans-serif;\">Riferimenti:<\/span><\/small><\/p>\n<p><small>James Bridle, New Dark Age. Technology and the End of the Future (Verso, 2018).<\/small><\/p>\n<p><small>Rosa Menkman, The Glitch Moment(um) (Institute of Network Cultures, 2011).<\/small><\/p>\n<p><small>Trevor Paglen, \u201cSociety of the Psyop, Part 2: AI, Mind Control, and Magic,\u201d e-flux Journal, n. 148, ottobre 2024.<\/small><\/p>\n<p><small>Trevor Pagelan, &#8220;Society of the Psyop, Part 3: Cognition and Chaos,\" <em>e-flux Journal<\/em>, no. 149, novembre, 2024.<\/small><\/p>\n<p><small>Hito Steyerl, Medium Hot: Images in the Age of Heat (Verso Books, 2025).<\/small><\/p>\n<p>\n<\/div><\/div><\/div><\/div><\/div><\/section><section class=\"kc-elm kc-css-752136 kc_row\"><div class=\"kc-row-container  kc-container\"><div class=\"kc-wrap-columns\"><div class=\"kc-elm kc-css-582768 kc_col-sm-12 kc_column kc_col-sm-12\"><div class=\"kc-col-container\"><div class=\"kc-elm kc-css-377929\" style=\"height: 50px; clear: both; width:100%;\"><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"kc-elm kc-css-125325 kc_row\"><div class=\"kc-row-container  kc-container\"><div class=\"kc-wrap-columns\"><div class=\"kc-elm kc-css-581417 kc_col-sm-6 kc_column kc_col-sm-6\"><div class=\"kc-col-container\"><div class=\"kc-elm kc-css-435872 kc_text_block\"><\/p>\n<h4>NUOVO ORARIO DURANTE LA MOSTRA:<\/h4>\n<ul>\n<li>Luned\u00ec\u2013venerd\u00ec: 16.00\u201320.00<\/li>\n<li>Sabato e domenica: 10.00\u201313.00, 17.00\u201320.00<\/li>\n<\/ul>\n<p>\n<\/div><\/div><\/div><div class=\"kc-elm kc-css-403623 kc_col-sm-6 kc_column kc_col-sm-6\"><div class=\"kc-col-container\"><div class=\"kc-elm kc-css-50323 kc_text_block\"><\/p>\n<h4>VISITE GUIDATE:<\/h4>\n<ul>\n<li><strong>18 ottobre alle 11.00<\/strong>, Galleria Loggia<\/li>\n<li><strong>24 ottobre alle 17.00<\/strong>, Galleria Loggia<\/li>\n<li><strong>31 ottobre alle 17.00<\/strong>, Galleria Loggia<\/li>\n<\/ul>\n<p>\n<\/div><\/div><\/div><\/div><\/div><\/section><section class=\"kc-elm kc-css-81098 kc_row\"><div class=\"kc-row-container  kc-container\"><div class=\"kc-wrap-columns\"><div class=\"kc-elm kc-css-676939 kc_col-sm-12 kc_column kc_col-sm-12\"><div class=\"kc-col-container\"><div class=\"kc-elm kc-css-384444\" style=\"height: 100px; clear: both; width:100%;\"><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"kc-elm kc-css-405624 kc_row\"><div class=\"kc-row-container  kc-container\"><div class=\"kc-wrap-columns\"><div class=\"kc-elm kc-css-660090 kc_col-sm-3 kc_column kc_col-sm-3\"><div class=\"kc-col-container\"><div class=\"kc-elm kc-css-478872 kc_shortcode kc_single_image\">\n\n        <img decoding=\"async\" src=\"https:\/\/www.obalne-galerije.si\/wp-content\/uploads\/2025\/10\/FEED-1080x1350-2025-IG-STORIES-1080x1920-1.jpg\" class=\"\" alt=\"\" \/>    <\/div>\n<\/div><\/div><div class=\"kc-elm kc-css-457956 kc_col-sm-3 kc_column kc_col-sm-3\"><div class=\"kc-col-container\"><\/div><\/div><div class=\"kc-elm kc-css-91132 kc_col-sm-3 kc_column kc_col-sm-3\"><div class=\"kc-col-container\"><\/div><\/div><div class=\"kc-elm kc-css-5780 kc_col-sm-3 kc_column kc_col-sm-3\"><div class=\"kc-col-container\"><\/div><\/div><\/div><\/div><\/section><\/p>\n","protected":false},"excerpt":{"rendered":"<p>13\u00b0 Festival d\u2019arte contemporanea e intermediale IZIS:FINE DEL MESSAGGIO |\u00a0 Galleria Loggia, Capodistria, 17 ottobre \u2013 2 novembre 2025 |\u00a0Inaugurazione: 17 ottobre, ore 19:00 |\u00a0 Artiste e artisti: Sara Bezov\u0161ek e Dorijan \u0160i\u0161ko, Sanela Jahi\u0107, PlateauResidue + Samo Kutin ed Enja Grabijan, \u0160pela Petri\u010d, Maja Smrekar |\u00a0 Curatrice: Irena Bori\u0107.<\/p>\n","protected":false},"author":4,"featured_media":26135,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34,42,80,48],"tags":[],"class_list":["post-26032","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi","category-galleria-loza","category-mostre","category-notizie"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.obalne-galerije.si\/it\/wp-json\/wp\/v2\/posts\/26032","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.obalne-galerije.si\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.obalne-galerije.si\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.obalne-galerije.si\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.obalne-galerije.si\/it\/wp-json\/wp\/v2\/comments?post=26032"}],"version-history":[{"count":4,"href":"https:\/\/www.obalne-galerije.si\/it\/wp-json\/wp\/v2\/posts\/26032\/revisions"}],"predecessor-version":[{"id":26141,"href":"https:\/\/www.obalne-galerije.si\/it\/wp-json\/wp\/v2\/posts\/26032\/revisions\/26141"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.obalne-galerije.si\/it\/wp-json\/wp\/v2\/media\/26135"}],"wp:attachment":[{"href":"https:\/\/www.obalne-galerije.si\/it\/wp-json\/wp\/v2\/media?parent=26032"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.obalne-galerije.si\/it\/wp-json\/wp\/v2\/categories?post=26032"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.obalne-galerije.si\/it\/wp-json\/wp\/v2\/tags?post=26032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}