{"id":17303,"date":"2023-03-06T15:46:15","date_gmt":"2023-03-06T14:46:15","guid":{"rendered":"https:\/\/www.obalne-galerije.si\/?p=17303"},"modified":"2023-08-23T15:34:34","modified_gmt":"2023-08-23T13:34:34","slug":"la-piazza-dei-non-indiferrenti-nemanja-cvijanovic","status":"publish","type":"post","link":"https:\/\/www.obalne-galerije.si\/it\/la-piazza-dei-non-indiferrenti-nemanja-cvijanovic\/","title":{"rendered":"NEMANJA CVIJANOVI\u0106: LA PIAZZA DEI NON INDIFFERENTI"},"content":{"rendered":"<p><section class=\"kc-elm kc-css-691684 kc_row\"><div class=\"kc-row-container  kc-container\"><div class=\"kc-wrap-columns\"><div class=\"kc-elm kc-css-570347 kc_col-sm-6 kc_column kc_col-sm-6\"><div class=\"kc-col-container\"><div class=\"kc-elm kc-css-420894 kc_shortcode kc_single_image\">\n\n        <img decoding=\"async\" src=\"https:\/\/www.obalne-galerije.si\/wp-content\/uploads\/2023\/03\/Cvijanovic_plakat-pdf.jpg\" class=\"\" alt=\"\" \/>    <\/div>\n<div class=\"kc-elm kc-css-335842\" style=\"height: 20px; clear: both; width:100%;\"><\/div>\n<div class=\"kc-elm kc-css-877026\">\n\t<a class=\"kc_button\" href=\"https:\/\/www.obalne-galerije.si\/wp-content\/uploads\/2023\/03\/NC_vabilo_TISK.pdf\" target=\"_self\" title=\"\" onclick=\"\">\n\t\t<i class=\"sl-paper-clip\"><\/i> INVITO: DOWNLOAD\t<\/a>\n<\/div>\n<div class=\"kc-elm kc-css-667378\" style=\"height: 20px; clear: both; width:100%;\"><\/div>\n<div class=\"kc-elm kc-css-230465\">\n\t<a class=\"kc_button\" href=\"https:\/\/drive.google.com\/drive\/folders\/1UMcJnjbRw4ZGu9Bc6Gpul0Gu0WhntGRm?usp=sharing\" target=\"_self\" title=\"\" onclick=\"\">\n\t\t<i class=\"sl-folder-alt\"><\/i> CARTELLA STAMPA: DOWNLOAD\t<\/a>\n<\/div>\n<div class=\"kc-elm kc-css-890474\" style=\"height: 30px; clear: both; width:100%;\"><\/div>\n<div class=\"kc-elm kc-css-165743\">\n\t<a class=\"kc_button\" href=\"https:\/\/www.obalne-galerije.si\/wp-content\/uploads\/2023\/03\/NC_press_ITA.pdf\" target=\"_self\" title=\"\" onclick=\"\">\n\t\t<i class=\"et-magnifying-glass\"><\/i> INFORMAZIONI MOSTRA\t<\/a>\n<\/div>\n<div class=\"kc-elm kc-css-316600\" style=\"height: 30px; clear: both; width:100%;\"><\/div><\/div><\/div><div class=\"kc-elm kc-css-259218 kc_col-sm-6 kc_column kc_col-sm-6\"><div class=\"kc-col-container\"><div class=\"kc-elm kc-css-724274 kc_text_block\"><\/p>\n<p><strong>NEMANJA CVIJANOVI\u0106: LA PIAZZA DEI NON INDIFFERENTI |\u00a0<\/strong><\/p>\n<p><strong>Retrospettiva \u2013 Galleria Loggia, Galleria Medusa e Magazzino Libertas, Capodistria, Galleria civica Pirano, 25.03.\u250021.05.2023 |\u00a0<\/strong><\/p>\n<p><strong>Conferenza stampa: Venerd\u00ec, 24.03.2023, alle 11.00 nella Galleria civica Pirano |\u00a0<\/strong><\/p>\n<p><strong>Inaugurazione della mostra: Sabato, 25.03.2023, alle 12.00 nella Galleria Loggia Capodistria |\u00a0<\/strong><\/p>\n<p><strong>Curatrice: dott.ssa Majda Bo\u017eeglav Japelj<\/strong><\/p>\n<p><!--more--><\/p>\n<p>\n<\/div>\n<div class=\"kc-elm kc-css-76197 divider_line\">\n\t<div class=\"divider_inner divider_line1\">\n\t\t\t<\/div>\n<\/div>\n<div class=\"kc-elm kc-css-16079 kc_text_block\"><\/p>\n<p>La mostra antologica dell&#039;artista croato <strong>Nemanja Cvijanovi\u0107<\/strong> apre ufficialmente il ricco programma espositivo delle Gallerie costiere di Pirano previsto per l\u2019anno 2023. <strong><em>La piazza dei non indifferenti<\/em><\/strong> rappresenta la prima grande presentazione delle opere di questo artista in Slovenia e in un pi\u00f9 ampio contesto europeo.<\/p>\n<p>Nemanja Cvijanovi\u0107 \u00e8 annoverato tra i principali artisti concettuali croati della generazione di mezzo. Con il suo lavoro offre un approccio fresco e innovativo alla comprensione dell\u2019impegno dell&#039;artista e dell&#039;arte nella pratica visiva contemporanea, dove dimostra di essere critico senza compromessi e ribelle in modo radicale, ma anche sottilmente ironico e brillante.<br \/>Curata dalla dott.ssa <strong>Majda Bo\u017eeglav Japelj<\/strong>, la mostra intitolata\u00a0<em>La piazza dei non indifferenti<\/em>\u00a0\u00e8 il risultato della selezione, realizzata dall&#039;autore, di opere chiave appartenenti al fruttuoso periodo creativo ed espositivo di due decenni.<\/p>\n<p>La produzione di questa gradne retrospettiva \u00e8 resa possibile grazie alla collaborazione con numerosi partner, tra cui il <strong>Comune di Pirano<\/strong>, la <strong>Citt\u00e0 Comune di Capodistria<\/strong>, il <strong>Ministero della Cultura della Repubblica di Slovenia<\/strong>, il <strong>Ministero della Cultura della Repubblica di Croazia<\/strong>, il <strong>Comune di Fiume<\/strong>, il <strong>MMSU, Museo d&#039;arte moderna e contemporanea di Fiume<\/strong>, il <strong>Museo civico di Fiume<\/strong> e <strong>la Fondazione Rosa Luxemburg Stiftung Belgrado<\/strong>. Particolarmente preziosa \u00e8 la collaborazione con le istituzioni museali croate, che grazie ai prestiti ottenuti di opere conservate nelle loro collezioni, hanno permesso di arricchire la presentazione dell\u2019artista.<\/p>\n<p><strong>Nei quattro spazi espositivi di Pirano e Capodistria<\/strong>: la <strong>Galleria civica Pirano,<\/strong> le <strong>Galleria Medusa, Galleria Loggia<\/strong> e il <strong>Magazzino Libertas a Capodistria<\/strong> \u2013 verr\u00e0 presentata un&#039;ampia gamma di espressioni mediali: fotografie, dipinti, ceramiche, collage, video, grafiche, installazioni e creazioni multimediali.\u00a0<em><strong>Dolce Terrore,<\/strong><\/em><strong>\u00a0<em>Monumento a Fiume rossa, Seguitemi \u00a0compagni, evviva!, Un valzer?<\/em><\/strong>\u00a0sono solo alcuni degli impegnativi titoli delle opere. La loro disposizione in luoghi diversi non segue una sequenza cronologica, ma evidenzia l&#039;intenzione dell&#039;autore di cercare un&#039;adeguata installazione spaziale per le sue opere concettualmente forti in modo che possano stabilire un dialogo pieno di emozioni con lo spettatore.<\/p>\n<\/p>\n<p>Nell&#039;ambit<span style=\"font-style: inherit; font-family: -apple-system, BlinkMacSystemFont, &#039;Segoe UI&#039;, Roboto, Oxygen-Sans, Ubuntu, Cantarell, &#039;Helvetica Neue&#039;, sans-serif;\">o della preparazione del progetto, inoltre, ricordiamo che l&#039;anno scorso \u00a0si \u00e8 svolta presso l&#039;Accademia di Belle Arti di Venezia anche la presentazione del libro\u00a0<\/span><em style=\"font-family: -apple-system, BlinkMacSystemFont, &#039;Segoe UI&#039;, Roboto, Oxygen-Sans, Ubuntu, Cantarell, &#039;Helvetica Neue&#039;, sans-serif;\">L&#039;antifascismo come monumento autodifensivo<\/em><span style=\"font-style: inherit; font-family: -apple-system, BlinkMacSystemFont, &#039;Segoe UI&#039;, Roboto, Oxygen-Sans, Ubuntu, Cantarell, &#039;Helvetica Neue&#039;, sans-serif;\">\u00a0(editori: Rosa Luxemburg Stiftung Belgrado, Museo di arte moderna e contemporanea Fiume e Gallerie costiere Pirano).<\/span><\/p>\n<p><strong>Una parte integrante del progetto espositivo \u00e8 costituita da un programma di visite guidate guide e laboratori specialistici per gli studenti di arti visive dell&#039;Universit\u00e0 del Litorale (PEF VUO). Il programma della date verr\u00e0 pubblicato prossimamente.<\/strong><\/p>\n<p><strong>Nemanja Cvijanovi\u0107<\/strong>\u00a0(Fiume, 1972) \u00e8 un artista multimediale croato che lavora nel campo della video arte, della fotografia, della performance e dell&#039;arte concettuale. Cvijanovi\u0107 si \u00e8 laureato nel 1998 presso l\u2019Accademia di Belle Arti di Venezia (professori: Tiozzo G. B., Patelli P., Di Raco C.). Nel 2010 ha completato la formazione magistrale presso la Facolt\u00e0 di Design e Arti dell\u2019Universit\u00e0 IUAV di Venezia. \u00c8 membro dell\u2019Associazione croata degli artisti visivi (HDLU) di Fiume. Collabora professionalmente con la Galleria T293 di Napoli. Lavora come artista-curatore dal 2009, quando insieme ai suoi colleghi ha fondato la galleria internazionale SIZ (Comunit\u00e0 d&#039;interesse autogestita) a Fiume. \u00c8 docente all&#039;Accademia di Belle Arti di Venezia e\u00a0 all&#039;Universit\u00e0 del Litorale, Facolt\u00e0 di studi educativi (UP PEF), il programma di studio Arti visive e design (VUO) a Capodistria. Ha esposto in diverse mostre personali e collettive in Croazia e nel mondo, in Italia, Austria, Belgio, Bosnia ed Erzegovina, Francia, Cina, Russia, Gran Bretagna, Svizzera, Corea, USA, Norvegia\u2026 Per il suo lavoro \u00e8 stato pi\u00f9 volte premiato. Vive e lavora tra Fiume e Venezia.<\/p>\n<p>\n<\/div>\n<div class=\"kc-elm kc-css-158220 divider_line\">\n\t<div class=\"divider_inner divider_line1\">\n\t\t\t<\/div>\n<\/div>\n<\/div><\/div><\/div><\/div><\/section><section class=\"kc-elm kc-css-937301 kc_row\"><div class=\"kc-row-container  kc-container\"><div class=\"kc-wrap-columns\"><div class=\"kc-elm kc-css-195743 kc_col-sm-6 kc_column kc_col-sm-6\"><div class=\"kc-col-container\"><div class=\"kc-elm kc-css-480463\" style=\"height: 50px; clear: both; width:100%;\"><\/div><div class=\"kc-elm kc-css-321877 kc_shortcode kc_single_image\">\n\n        <a rel=\"prettyPhoto\" class=\"kc-pretty-photo\" href=\"https:\/\/www.obalne-galerije.si\/wp-content\/uploads\/2023\/03\/4_Mount-Triglav-on-The-Adriatic-Sea-2010-scaled.jpg\" title=\"\" target=\"\">\n        <img decoding=\"async\" src=\"https:\/\/www.obalne-galerije.si\/wp-content\/uploads\/2023\/03\/4_Mount-Triglav-on-The-Adriatic-Sea-2010-scaled.jpg\" class=\"\" alt=\"\" \/>    <\/a>\n    <\/div>\n<div class=\"kc-elm kc-css-280412 kc_text_block\"><\/p>\n<p><em>Mount Triglav on the Adriatic Sea<\/em>, 2010, fotografia della performance<\/p>\n<p>\n<\/div><div class=\"kc-elm kc-css-918921 kc_shortcode kc_single_image\">\n\n        <img decoding=\"async\" src=\"https:\/\/www.obalne-galerije.si\/wp-content\/uploads\/2023\/03\/8_La-Repubblica-2007-scaled.jpg\" class=\"\" alt=\"\" \/>    <\/div>\n<div class=\"kc-elm kc-css-740481 kc_text_block\"><\/p>\n<p><em>La Repubblica<\/em>, 2007, luci neon<\/p>\n<p>\n<\/div><div class=\"kc-elm kc-css-530447 kc_shortcode kc_single_image\">\n\n        <a rel=\"prettyPhoto\" class=\"kc-pretty-photo\" href=\"https:\/\/www.obalne-galerije.si\/wp-content\/uploads\/2023\/03\/6_Ste-morda-za-valcek_.jpg\" title=\"\" target=\"\">\n        <img decoding=\"async\" src=\"https:\/\/www.obalne-galerije.si\/wp-content\/uploads\/2023\/03\/6_Ste-morda-za-valcek_.jpg\" class=\"\" alt=\"\" \/>    <\/a>\n    <\/div>\n<div class=\"kc-elm kc-css-379964 kc_text_block\"><\/p>\n<p><em>Un Valzer?<\/em> ,2014, ceramica, acrilico, stoffa, spugna, paglia<\/p>\n<p>\n<\/div><\/div><\/div><div class=\"kc-elm kc-css-270599 kc_col-sm-6 kc_column kc_col-sm-6\"><div class=\"kc-col-container\"><div class=\"kc-elm kc-css-549875\" style=\"height: 50px; clear: both; width:100%;\"><\/div>\n<div class=\"kc-elm kc-css-754646 kc-title-wrap \">\n\n\t<h3 class=\"kc_title\">INFORMAZIONI SUL PERCORSO ESPOSITIVO\r\n<\/h3>\n<\/div>\n<div class=\"kc-elm kc-css-999317\" style=\"height: 20px; clear: both; width:100%;\"><\/div><div class=\"kc-elm kc-css-601583 kc_text_block\"><\/p>\n<h4>Galleria Civica Pirano<\/h4>\n<\/p>\n<p>La Galleria civica Pirano dispone di numerose opere \u2013 collage, video, grafiche, dipinti, installazioni e creazioni multimediali realizzate tra il 2002 e il 2019\u00a0\u2013\u00a0dove \u00e8 facile riconoscere il caratteristico linguaggio visivo dell\u2019artista. Nelle sue opere, Cvijanovi\u0107\u00a0tocca temi di attualit\u00e0\u00a0politica, economica e sociale, anche nell\u2019ambito del sistema d\u2019arte, associandoli e confrontandoli con la storia passata e recente. Un argomento a lui particolarmente caro \u00e8 il processo di transizione dal sistema ideologicamente indottrinato dell\u2019ex patria comune, alla societ\u00e0\u00a0senza compromessi del capitalismo neoliberale.<\/p>\n<p>L\u2019atteggiamento critico ma senza falsi sentimentalismi di Cvijanovi\u0107, affronta l\u2019ostilit\u00e0\u00a0presente nell\u2019odierna societ\u00e0\u00a0che rifiuta la memoria dell\u2019identit\u00e0\u00a0collettiva e personale del passato, negando anche i valori positivi, come: \u00bbl\u2019equit\u00e0, la fede in un futuro luminoso, la fratellanza e l\u2019unit\u00e0, la pace\u2026\u00ab \u00c8 attratto dall\u2019estetica dei simboli e dal fenomeno della memoria collettiva, che attraverso la linea temporale della propaganda, acquista nelle sue opere significati completamente diversi.<\/p>\n<p>La tagliente presa di posizione critica nelle opere che utilizzano il simbolismo dei segni \u00e8 in certi luoghi eloquente in modo doloroso (<em>Natura morta, Fasci al muro, All Right, La Repubblica<\/em>\u00a0\u2026), altrove velatamente ironica e caustica (<em>Do not fuck with Social Democracy,<\/em>\u00a0opere della serie di stemmi\u2026). Si posizionano invece nella sfera di piccole storie personali e apparentemente insignificanti, nell\u2019interpretazione di eventi storici recenti nell\u2019ex patria comune, le due opere\u00a0<em>Seguitemi compagni, evviva!\u00a0<\/em>e\u00a0<em>Una e tre sedie.<\/em>\u00a0In entrambi i casi, l\u2019autore ha utilizzato reperti museali del Museo civico di Fiume e li ha collocati in funzione di oggetti\u00a0<em>ready made\u00a0<\/em>nella realt\u00e0\u00a0della propria creazione multimediale.<\/p>\n<p><span style=\"font-weight: bold;\">Orari d&#039;apertura<\/span>: <a href=\"https:\/\/www.obalne-galerije.si\/it\/galleria-civica\/\">https:\/\/www.obalne-galerije.si\/it\/galleria-civica\/<\/a><\/p>\n<p>\n<\/div><div class=\"kc-elm kc-css-254817\" style=\"height: 20px; clear: both; width:100%;\"><\/div><div class=\"kc-elm kc-css-348639 kc_text_block\"><\/p>\n<h4><span lang=\"SL\">Galleria Loggia, Capodistria<\/span><\/h4>\n<\/p>\n<p>L\u2019opus operandi di Cvijanovi\u0107 \u00e8 caratterizzato anche da opere destinate agli spazi pubblici particolari.<em>\u00a0Il Monumento al Fiume rosso \u2013 monumento all<\/em><em>\u2019<\/em><em>autodifesa<\/em>\u00a0esposto nella Galleria Loggia a Capodistria \u00e8 stato creato nell\u2019ambito del progetto\u00a0<em>Fiume 2020 \u2013 Capitale europea della cultura<\/em>. L\u2019installazione di una stella in cemento armato, ferro e vetro sul grattacielo cittadino evoca il ricordo di un\u2019impresa simile gi\u00e0\u00a0avvenuta durante la liberazione della citt\u00e0\u00a0nel 1945.<\/p>\n<p>\u201cMonumento alla memoria e alla crisi di memoria\u201d, come l\u2019opera \u00e8 stata sinteticamente descritta nel catalogo dell\u2019evento, rappresenta una stella a cinque punte recuperata, trafitta da 2.800 frammenti di vetro rosso sulla sua superficie bianca (tanti sono i combattenti morti nella battaglia di Fiume). Quest\u2019installazione di grandi dimensioni di Cvijanovi\u0107\u00a0ha turbato gli spiriti con il peso ideologico del suo apparire per tutta la durata della sua esposizione. Sembra per\u00f2 che l\u2019autore rendendosi conto dell\u2019impatto della sua opera, abbia incorporato in anticipo all\u2019interno del suo nucleo tutte le reazioni del pubblico e le percezioni della cerchia pubblica pi\u00f9 ampia, ivi compresi i taglienti frammenti di vetro con cui, in previsione di attacchi vandalici, ha corredato la sua superficie.<\/p>\n<p>La rilevanza della sua scultura sociale non si \u00e8 esaurita al termine del primo evento performativo. Anche nelle installazioni successive, in questo caso nelle aree limitate degli spazi della galleria, il discorso critico dell\u2019artista si rinnova e si rafforza nuovamente. La mostra viene completata da un dettagliato catalogo, una monografia, dove sono descritti la cronologia degli eventi, la copertura mediatica e gli interventi scritti da vari autori che hanno esplorato in profondit\u00e0\u00a0il contesto socio-politico della posizione dell\u2019artista.<br \/><strong><em><br \/><\/em><\/strong><\/p>\n<p><strong>Orari d&#039;apertu<\/strong><strong>ra: <\/strong><a href=\"https:\/\/www.obalne-galerije.si\/it\/galleria-loggia\/\">https:\/\/www.obalne-galerije.si\/it\/galleria-loggia\/<\/a><\/p>\n<p>\n<\/div><div class=\"kc-elm kc-css-544653\" style=\"height: 20px; clear: both; width:100%;\"><\/div><div class=\"kc-elm kc-css-629890 kc_text_block\"><\/p>\n<h4>Magazzino Libertas, Capodistria<\/h4>\n<\/p>\n<p>Nell\u2019ampio Magazzino Libertas, Cvijanovi\u0107\u00a0ha realizzato quella parte della sua essenza di artista in cui lo riconosciamo come un tipico rappresentante dell\u2019\u00bbestetica dell\u2019attivismo\u00ab. Attraverso attivit\u00e0\u00a0interattive nello spazio pubblico e urbano, in cui entra in cooperazione con gruppi eterogenei, appare nel ruolo di un artista responsabile e consapevole che si oppone alle anomalie dei sistemi sociali moderni, critica le strutture ideologiche e nelle sue ricostruzioni guida lo spettatore ad un\u2019autoriflessione interiorizzata.<\/p>\n<p>L\u2019installazione video e spaziale intitolata\u00a0<em>Applauso\u00a0<\/em>(2009)\u00a0\u00e8 legata al progetto realizzato nel 2009 nell\u2019ambito di\u00a0<em>Operazione citt\u00e0<\/em>\u00a0\u2013 una manifestazione della scena indipendente di Zagabria. Cvijanovi\u0107\u00a0ha assunto duecento cittadini per una protesta organizzata in una piazza zagabrese, che hanno ricevuto il compenso dopo avere espresso pubblicamente per un\u2019ora le loro opinioni. Durante lo svolgimento della protesta, non \u00e8 stato possibile capire il perch\u00e9\u00a0del raduno, in quanto gli striscioni portavano slogan di varie posizioni politiche, apolitiche, utopiche, femministe, idealiste, fino alle meta posizioni che riguardavano la protesta in corso, come per esempio lo striscione\u00a0<em>Chi tace acconsente!\u00a0<\/em>L\u2019artista ha messo i manifestanti nella posizione in cui avrebbero dovuto trovarsi, come individui impegnati contro le decisioni inaccettabili e antidemocratiche degli apparati di potere dominanti; ha proiettato quindi il proprio attivismo su un gruppo pi\u00f9 ampio, si \u00e8 infiltrato nella loro coscienza e ha innescato dentro di loro una sottile riflessione critica sui concetti di potere, autorit\u00e0, divieto e responsabilit\u00e0\u00a0personale e collettiva.<\/p>\n<p>L\u2019installazione a parete\u00a0<em>Pago l<\/em><em>\u2019<\/em><em>elettricit\u00e0\u00a0<\/em>\u00e8 una lastra di marmo che riassume in origine la forma e il contenuto della lapide di Josip Broz Tito, ex statista jugoslavo e leader comunista (1892-1980), a Dedinje, Belgrado. Cvijanovi\u0107\u00a0ha convertito un pezzo di marmo di Carrara in un radiatore da parete per uso domestico, un metodo di riscaldamento comune in Jugoslavia dopo la seconda guerra mondiale. Con l\u2019intento di avvicinare l\u2019arte al mondo reale, secondo il principio del\u00a0<em>ready made<\/em>, l\u2019autore ha utilizzato un\u2019icona socialista rappresentativa, privandola apparentemente della caratteristica primaria del monumento, pi\u00f9 precisamente \u2013 conferendole la forma di un dispositivo di riscaldamento, l\u2019ha aggiornata funzionalmente. Un nuovo emblema con un nuovo ruolo gioca maliziosamente con i rituali dei pellegrinaggi di massa lungo i percorsi degli oggetti di culto e allo stesso tempo interviene nell\u2019immaginario collettivo dell\u2019interpretazione del ricordo di quel periodo storico.<\/p>\n<p><strong>Orari d&#039;apertura:<br \/><\/strong><em>Marted\u00ec \u2013 Venerd\u00ec: 16.00 \u2013 19.00<br \/><\/em><em>Sabato: 12.00-19.00<\/em><\/p>\n<p>\n<\/div><div class=\"kc-elm kc-css-796088\" style=\"height: 20px; clear: both; width:100%;\"><\/div><div class=\"kc-elm kc-css-811497 kc_text_block\"><\/p>\n<h4>Galleria Medusa, Capodistria<\/h4>\n<\/p>\n<p>Negli spazi della Galleria Medusa di Capodistria troviamo espressioni mediali e soluzioni tematiche completamente diverse. Ci sono l\u2019opera sonora ambientale\u00a0<em>Un Valzer?<\/em>\u00a0e una applique luminosa a forma di stemma italiano con il titolo\u00a0<em>La Repubblica<\/em>. Il neon, che in genere definisce lo spazio urbano e si trova negli elaborati della storia recente dell\u2019arte contemporanea, \u00e8 una scelta frequente di Cvijanovi\u0107, di regola al servizio della sua radicale posizione socialmente critica con una spiccata nota ironica. L\u2019esibizione delle insegne di stato della Repubblica Italiana in una scintillante veste al neon, fa loro perdere la seriet\u00e0\u00a0di emblemi statali e fa venire in mente uno slogan pubblicitario che fa pensare al consumismo nocivo e onnipresente nella struttura della societ\u00e0\u00a0moderna.<\/p>\n<p>\u00a0<em>Un Valzer?<\/em>\u00a0\u00e8 il titolo suggestivo dell\u2019installazione ambientale e sonora, per la quale l\u2019autore ha scelto i motivi di tre film cult di altrettanti registi (Fernando Arrabal,\u00a0<em>The Guernica Tree<\/em>; Pier Paolo Pasolini,\u00a0<em>Sal\u00f2 o le 120 giornate di Sodoma<\/em>; Mario Martone,\u00a0<em>La salita<\/em>). Sei figure danzanti portano il peso del contenuto di film selezionati: il dramma della guerra civile spagnola attraverso la storia d\u2019amore di una coppia; il soggetto aspro, difficile e ancora oggi controverso del film\u00a0<em>Sal\u00f2 o le 120 giornate di Sodoma<\/em>; l\u2019episodio del cortometraggio\u00a0<em>La salita<\/em>, immerso nell\u2019atmosfera onirica del paesaggio vulcanico, lo scenario surreale in cui, sotto il peso di responsabilit\u00e0\u00a0e dilemmi ideologici, si trova il sindaco democratico di Napoli.<\/p>\n<p>Le figure in ceramica, alte diverse decine di centimetri con dettagli minuziosi e realizzate con materiali diversi, sono progettate nello stile naturalistico dell\u2019estetica artigianale tradizionale del sud italiano. La rappresentazione scenica di singole coppie danzanti in un vortice di valzer leggero \u00e8\u00a0un\u2019esca, ma anche una manipolazione intuitiva, con la quale l\u2019autore ci costringe a riconsiderare i temi sempre attuali della narrazione cinematografica scelta.<br \/><strong><em><br \/><\/em><\/strong><\/p>\n<p><strong>Orari d&#039;apertura<em>: <\/em><\/strong><a href=\"https:\/\/www.obalne-galerije.si\/it\/galleria-medusa\/\">https:\/\/www.obalne-galerije.si\/it\/galleria-medusa\/<\/a><\/p>\n<p>\n<\/div><div class=\"kc-elm kc-css-65812\" style=\"height: 20px; clear: both; width:100%;\"><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"kc-elm kc-css-607831 kc_row\"><div class=\"kc-row-container  kc-container\"><div class=\"kc-wrap-columns\"><div class=\"kc-elm kc-css-257679 kc_col-sm-12 kc_column kc_col-sm-12\"><div class=\"kc-col-container\"><div class=\"kc-elm kc-css-67713\" style=\"height: 20px; clear: both; width:100%;\"><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"kc-elm kc-css-472342 kc_row\"><div class=\"kc-row-container  kc-container\"><div class=\"kc-wrap-columns\"><div class=\"kc-elm kc-css-768253 kc_col-sm-4 kc_column kc_col-sm-4\"><div class=\"kc-col-container\"><div class=\"kc-elm kc-css-208206 kc_shortcode kc_single_image\">\n\n        <img decoding=\"async\" src=\"https:\/\/www.obalne-galerije.si\/wp-content\/uploads\/2023\/03\/48A7784-2-scaled.jpg\" class=\"\" alt=\"\" \/>    <\/div>\n<\/div><\/div><div class=\"kc-elm kc-css-742686 kc_col-sm-4 kc_column kc_col-sm-4\"><div class=\"kc-col-container\"><div class=\"kc-elm kc-css-442981 kc_shortcode kc_single_image\">\n\n        <img decoding=\"async\" src=\"https:\/\/www.obalne-galerije.si\/wp-content\/uploads\/2023\/03\/48A7860-2-scaled.jpg\" class=\"\" alt=\"\" \/>    <\/div>\n<\/div><\/div><div class=\"kc-elm kc-css-875836 kc_col-sm-4 kc_column kc_col-sm-4\"><div class=\"kc-col-container\"><div class=\"kc-elm kc-css-530759 kc_shortcode kc_single_image\">\n\n        <img decoding=\"async\" src=\"https:\/\/www.obalne-galerije.si\/wp-content\/uploads\/2023\/03\/48A7847-2-scaled.jpg\" class=\"\" alt=\"\" \/>    <\/div>\n<\/div><\/div><\/div><\/div><\/section><section class=\"kc-elm kc-css-399125 kc_row\"><div class=\"kc-row-container  kc-container\"><div class=\"kc-wrap-columns\"><div class=\"kc-elm kc-css-417059 kc_col-sm-12 kc_column kc_col-sm-12\"><div class=\"kc-col-container\"><div class=\"kc-elm kc-css-751618\" style=\"height: 20px; clear: both; width:100%;\"><\/div><\/div><\/div><\/div><\/div><\/section><\/p>\n","protected":false},"excerpt":{"rendered":"<p>NEMANJA CVIJANOVI\u0106: LA PIAZZA DEI NON INDIFFERENTI |\u00a0 Retrospettiva \u2013 Galleria Loggia, Galleria Medusa e Magazzino Libertas, Capodistria, Galleria civica Pirano, 25.03.\u250021.05.2023 |\u00a0 Conferenza stampa: Venerd\u00ec, 24.03.2023, alle 11.00 nella Galleria civica Pirano |\u00a0 Inaugurazione della mostra: Sabato, 25.03.2023, alle 12.00 nella Galleria Loggia Capodistria |\u00a0 Curatrice: dott.ssa Majda Bo\u017eeglav Japelj<\/p>\n","protected":false},"author":4,"featured_media":17723,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46,42,80,48],"tags":[],"class_list":["post-17303","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-galleria-civica","category-galleria-loza","category-mostre","category-notizie"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.obalne-galerije.si\/it\/wp-json\/wp\/v2\/posts\/17303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.obalne-galerije.si\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.obalne-galerije.si\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.obalne-galerije.si\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.obalne-galerije.si\/it\/wp-json\/wp\/v2\/comments?post=17303"}],"version-history":[{"count":5,"href":"https:\/\/www.obalne-galerije.si\/it\/wp-json\/wp\/v2\/posts\/17303\/revisions"}],"predecessor-version":[{"id":18722,"href":"https:\/\/www.obalne-galerije.si\/it\/wp-json\/wp\/v2\/posts\/17303\/revisions\/18722"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.obalne-galerije.si\/it\/wp-json\/wp\/v2\/media\/17723"}],"wp:attachment":[{"href":"https:\/\/www.obalne-galerije.si\/it\/wp-json\/wp\/v2\/media?parent=17303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.obalne-galerije.si\/it\/wp-json\/wp\/v2\/categories?post=17303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.obalne-galerije.si\/it\/wp-json\/wp\/v2\/tags?post=17303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}